{"id":357807,"date":"2025-05-10T20:31:35","date_gmt":"2025-05-10T18:31:35","guid":{"rendered":"https:\/\/hvc.de\/la-machine-dimpression-rapida-145-en-service-koenig-bauer-en-parle\/"},"modified":"2025-05-10T20:31:35","modified_gmt":"2025-05-10T18:31:35","slug":"la-machine-dimpression-rapida-145-en-service-koenig-bauer-en-parle","status":"publish","type":"post","link":"https:\/\/hvc.de\/fr\/la-machine-dimpression-rapida-145-en-service-koenig-bauer-en-parle\/","title":{"rendered":"La machine d&rsquo;impression Rapida 145 en service : Koenig &amp; Bauer en parle"},"content":{"rendered":"<h2>HVC f\u00eate l&rsquo;inauguration de la Rapida 145, son 150e anniversaire et sa nouvelle propri\u00e9t\u00e9<\/h2>\n<p>&nbsp;<\/p>\n<p>2020 a \u00e9t\u00e9 une ann\u00e9e pleine de revers en raison du grave incendie qui a touch\u00e9 HvC. C&rsquo;est d&rsquo;autant mieux qu&rsquo;il y a maintenant plusieurs raisons de faire la f\u00eate !<br \/>\n<!--more--><br \/>\nD&rsquo;une part, la nouvelle machine d&rsquo;impression Rapida 145 a \u00e9t\u00e9 solennellement mise en service et est d\u00e9sormais utilis\u00e9e pour r\u00e9pondre \u00e0 vos commandes d&rsquo;impression. D&rsquo;autre part, nous avons profit\u00e9 de l&rsquo;occasion pour f\u00eater les 150 ans de notre entreprise. Toutes ces festivit\u00e9s ont \u00e9galement \u00e9t\u00e9 l&rsquo;occasion pour notre directeur g\u00e9n\u00e9ral, J\u00fcrgen Bergmann, et notre directeur des ventes, Martin Trojca, d&rsquo;annoncer \u00e0 l&rsquo;entreprise que la propri\u00e9t\u00e9 de l&rsquo;entreprise familiale \u00e9tait pass\u00e9e \u00e0 la cinqui\u00e8me g\u00e9n\u00e9ration, Susanne Nordberg et Katharina Steffens. Nous f\u00e9licitons de tout c\u0153ur les propri\u00e9taires et envisageons ensemble un avenir florissant pour l&rsquo;entreprise !   <\/p>\n<p>Ces \u00e9v\u00e9nements n&rsquo;ont bien s\u00fbr pas \u00e9chapp\u00e9 au fabricant de notre machine \u00e0 imprimer Rapida 145, <a href=\"https:\/\/www.koenig-bauer.com\/de\/\" target=\"_blank\" rel=\"noopener\">Koenig &amp; Bauer<\/a>. Ceux-ci \u00e9crivent dans un communiqu\u00e9 de presse <\/p>\n<p style=\"text-align: left;\">\u00ab\u00a0&#8230;Il y a quelques jours, l&rsquo;entreprise d&#8217;emballage et de cartonnage Hubert von<\/p>\n<p style=\"text-align: left;\">Carnap \u00e0 Windeck\/Rh\u00e9nanie du Nord-Westphalie sa nouvelle presse offset \u00e0 feuilles<\/p>\n<p style=\"text-align: left;\">en compagnie de clients et de compagnons de route. Mais ce n&rsquo;est pas tout : <\/p>\n<p style=\"text-align: left;\">apr\u00e8s un sinistre d\u00fb \u00e0 un incendie l&rsquo;ann\u00e9e derni\u00e8re, la f\u00eate a donn\u00e9 l&rsquo;occasion de<\/p>\n<p>le 150e anniversaire de l&rsquo;entreprise qui n&rsquo;a pas pu \u00eatre c\u00e9l\u00e9br\u00e9. De plus, le directeur g\u00e9n\u00e9ral  <\/p>\n<p>J\u00fcrgen Bergmann et le directeur des ventes Martin Trojca collaborateurs et<\/p>\n<p>Nous souhaitons informer nos partenaires commerciaux qu&rsquo;avec Susanne Nordberg et Katharina Steffens<\/p>\n<p>la cinqui\u00e8me g\u00e9n\u00e9ration de l&rsquo;entreprise familiale en devient propri\u00e9taire.<\/p>\n<p>Avec cela et la nouvelle technique, l&rsquo;avenir de l&rsquo;entreprise de cartonnage est<\/p>\n<p>s\u00e9curis\u00e9&#8230;\u00a0\u00bb<\/p>\n<p>Lisez ici le communiqu\u00e9 de presse complet de Koenig &amp; Bauer sur la mise en service de la Rapida 145 :<\/p>\n<p><a href=\"https:\/\/www.hvc.de\/de\/wp-content\/uploads\/2021\/09\/Pressemitteilung-KBA-09.2021.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-1439\" src=\"https:\/\/www.hvc.de\/de\/wp-content\/uploads\/2021\/09\/Rapida-145-KBA.jpg\" alt=\"Communiqu\u00e9 de presse Rapida-145-KBA\" width=\"440\" height=\"622\" srcset=\"https:\/\/hvc.de\/wp-content\/uploads\/2021\/09\/Rapida-145-KBA.jpg 682w, https:\/\/hvc.de\/wp-content\/uploads\/2021\/09\/Rapida-145-KBA-600x849.jpg 600w, https:\/\/hvc.de\/wp-content\/uploads\/2021\/09\/Rapida-145-KBA-212x300.jpg 212w, https:\/\/hvc.de\/wp-content\/uploads\/2021\/09\/Rapida-145-KBA-103x146.jpg 103w, https:\/\/hvc.de\/wp-content\/uploads\/2021\/09\/Rapida-145-KBA-35x50.jpg 35w, https:\/\/hvc.de\/wp-content\/uploads\/2021\/09\/Rapida-145-KBA-57x80.jpg 57w\" sizes=\"(max-width: 440px) 100vw, 440px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>HVC f\u00eate l&rsquo;inauguration de la Rapida 145, son 150e anniversaire et sa nouvelle propri\u00e9t\u00e9 &nbsp; 2020 a \u00e9t\u00e9 une ann\u00e9e pleine de revers en raison du grave incendie qui a touch\u00e9 HvC. C&rsquo;est d&rsquo;autant mieux qu&rsquo;il y a maintenant plusieurs raisons de faire la f\u00eate !<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"","_seopress_redirections_param":"","_seopress_redirections_type":0,"_seopress_analysis_target_kw":"","inline_featured_image":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_feature_clip_id":0,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[143],"tags":[],"class_list":["post-357807","post","type-post","status-publish","format-standard","hentry","category-non-categorise"],"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"","_links":{"self":[{"href":"https:\/\/hvc.de\/fr\/wp-json\/wp\/v2\/posts\/357807","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hvc.de\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/hvc.de\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/hvc.de\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/hvc.de\/fr\/wp-json\/wp\/v2\/comments?post=357807"}],"version-history":[{"count":0,"href":"https:\/\/hvc.de\/fr\/wp-json\/wp\/v2\/posts\/357807\/revisions"}],"wp:attachment":[{"href":"https:\/\/hvc.de\/fr\/wp-json\/wp\/v2\/media?parent=357807"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/hvc.de\/fr\/wp-json\/wp\/v2\/categories?post=357807"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/hvc.de\/fr\/wp-json\/wp\/v2\/tags?post=357807"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}